{"id":69,"date":"2026-05-04T12:59:20","date_gmt":"2026-05-04T12:59:20","guid":{"rendered":"http:\/\/blin-energie.fr\/?page_id=69"},"modified":"2026-06-25T09:49:04","modified_gmt":"2026-06-25T09:49:04","slug":"monparcours","status":"publish","type":"page","link":"https:\/\/blin-energie.fr\/index.php\/monparcours\/","title":{"rendered":"Jean-Marie Blin"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"69\" class=\"elementor elementor-69\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7acd45e5 e-con-full elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"7acd45e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:995,&quot;url&quot;:&quot;http:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Photo-de-Jean-Marie-Blin37-e1781085225290.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t<div class=\"elementor-element elementor-element-6b47d410 e-con-full e-flex e-con e-child\" data-id=\"6b47d410\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a72d728 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4a72d728\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mon parcours<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7aad06 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d7aad06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-638b36c2 e-con-full e-flex e-con e-child\" data-id=\"638b36c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d4830c0 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6d4830c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D'un parcours de dirigeant \u00e0 l'accompagnement de l'\u00eatre : un chemin vers plus de sens, d'alignement et de transformation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ee40db elementor-widget elementor-widget-image\" data-id=\"4ee40db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3.png\" class=\"attachment-large size-large wp-image-683\" alt=\"constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3.png 512w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3-300x300.png 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-194ae8df elementor-widget elementor-widget-heading\" data-id=\"194ae8df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chemin constellation astrologie coaching<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a62b5d8 elementor-widget elementor-widget-spacer\" data-id=\"a62b5d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e2e04b2 e-con-full e-flex e-con e-child\" data-id=\"6e2e04b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<h2 data-interaction-id=\"8a55ecc\" class=\"e-8a55ecc-5f3afce e-heading-base\" data-e-type=\"widget\" data-id=\"8a55ecc\"><\/h2>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58bf1399 e-con-full elementor-hidden-desktop elementor-hidden-tablet e-flex e-con e-parent\" data-id=\"58bf1399\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:996,&quot;url&quot;:&quot;http:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Photo-de-Jean-Marie-Blin37-1-e1781085513628.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t<div class=\"elementor-element elementor-element-31be7968 e-con-full e-flex e-con e-child\" data-id=\"31be7968\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49ec6eb0 elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"49ec6eb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mon<br>parcours<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9c4caa elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b9c4caa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6f59a4 e-con-full e-flex e-con e-child\" data-id=\"a6f59a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67d98efc elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"67d98efc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\"font-size: 35px\">D'un parcours de dirigeant \u00e0 l'accompagnement de l'\u00eatre : un chemin vers plus de sens, d'alignement et de transformation<\/h2><br><br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ed53a4 elementor-widget elementor-widget-image\" data-id=\"9ed53a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-4.png\" class=\"attachment-large size-large wp-image-736\" alt=\"\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-4.png 512w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-4-300x300.png 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-4-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27666b2 e-con-full e-flex e-con e-child\" data-id=\"27666b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<h2 data-interaction-id=\"405cf5aa\" class=\"e-405cf5aa-fb175a4 e-heading-base\" data-e-type=\"widget\" data-id=\"405cf5aa\"><\/h2>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91bf44a elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"91bf44a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">chemin constellation astrologie coaching<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e12f253 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"e12f253\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-46495fe e-con-full e-flex e-con e-child\" data-id=\"46495fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd942b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4fd942b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123.jpg\" class=\"attachment-full size-full wp-image-1006\" alt=\"mon parcours constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123.jpg 1200w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123-300x200.jpg 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123-1024x683.jpg 1024w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c83202 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"8c83202\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4b72b8 elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"c4b72b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/blueline.json&quot;,&quot;id&quot;:677,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3836e7f e-con-full e-flex e-con e-child\" data-id=\"3836e7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-551640d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"551640d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un parcours riche et exigeant<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbcdbb0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"bbcdbb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"white-space: pre-wrap;\">Avant que mon chemin me plonge dans l&#8217;univers du coaching, de l&#8217;astrologie et des constellations, j&#8217;ai connu d&#8217;autres domaines. Pendant plus de 20 ans j&#8217;ai \u00e9volu\u00e9 dans des environnements exigeants. tels que la grande distribution, l&#8217;industrie chimique et agroalimentaire. J&#8217;y ai accompagn\u00e9 des \u00e9quipes jusqu&#8217;\u00e0 80 personnes et pilot\u00e9 des projets de transformation avec des r\u00e9sultats concrets et durables. Cette exp\u00e9rience m&#8217;a permis de d\u00e9velopper une approche \u00e0 la fois humaine, structur\u00e9 et profond\u00e9ment tourn\u00e9e vers l&#8217;accompagnement du changement.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0e376a elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"e0e376a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-110fd8f e-con-full e-flex e-con e-child\" data-id=\"110fd8f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d34c5eb elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d34c5eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123.jpg\" class=\"attachment-full size-full wp-image-1006\" alt=\"mon parcours constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123.jpg 1200w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123-300x200.jpg 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123-1024x683.jpg 1024w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin38-1-e1781085808123-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9528bc e-con-full e-flex e-con e-child\" data-id=\"c9528bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb751c1 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bb751c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un parcours riche et exigeant<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b31979 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"1b31979\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7cd7ec9 e-con-full e-flex e-con e-child\" data-id=\"7cd7ec9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-918bc96 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"918bc96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Pendant plus de 20 ans, j\u2019ai \u00e9volu\u00e9 dans des environnements exigeants tels que la grande distribution, l\u2019industrie chimique et l\u2019agroalimentaire.<br \/>J\u2019y ai accompagn\u00e9 des \u00e9quipes, manag\u00e9 jusqu\u2019\u00e0 80 personnes et pilot\u00e9 des projets de transformation avec des r\u00e9sultats concrets et durables.<br \/>Cette exp\u00e9rience m\u2019a permis de d\u00e9velopper une approche \u00e0 la fois humaine, structur\u00e9e et profond\u00e9ment tourn\u00e9e vers l\u2019accompagnement du changement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-521ee5e elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"521ee5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f9d609e e-con-full e-flex e-con e-child\" data-id=\"f9d609e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf262f7 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cf262f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La bascule<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-342a78a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"342a78a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"white-space: pre-wrap;\">Malgr\u00e9 cette r\u00e9ussite professionnelle, un vide silencieux qui persistait. Comme un appel int\u00e9rieur vers davantage de profondeur, de sens, d&#8217;alignement. En raison de ces sentiments, j&#8217;ai choisi de ralentir, de me recentrer et d&#8217;\u00e9couter cet \u00e9lan int\u00e9rieur qui demandait une autre mani\u00e8re d&#8217;\u00eatre au monde et aux autres.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-374ce3c e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"374ce3c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e2216f elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"9e2216f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/blueline.json&quot;,&quot;id&quot;:677,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ebf6429 e-con-full e-flex e-con e-child\" data-id=\"ebf6429\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac37d1f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"ac37d1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883.jpg\" class=\"attachment-full size-full wp-image-1008\" alt=\"mon parcours constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883.jpg 1200w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883-300x200.jpg 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883-1024x683.jpg 1024w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09f5e84 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"09f5e84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-187ab85 e-con-full e-flex e-con e-child\" data-id=\"187ab85\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae3e283 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ae3e283\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La bascule<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99867a7 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"99867a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883.jpg\" class=\"attachment-full size-full wp-image-1008\" alt=\"mon parcours constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883.jpg 1200w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883-300x200.jpg 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883-1024x683.jpg 1024w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin27-e1781085885883-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-313e18d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"313e18d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Malgr\u00e9 cette r\u00e9ussite professionnelle, un vide silencieux persistait.<br \/>Comme un appel int\u00e9rieur vers davantage de profondeur, de sens et d\u2019alignement.<br \/>J\u2019ai alors choisi de ralentir, de me recentrer et d\u2019\u00e9couter cet \u00e9lan int\u00e9rieur qui demandait une autre mani\u00e8re d\u2019\u00eatre au monde et aux autres.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcaa75a elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"dcaa75a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c4b4b8b e-con-full e-flex e-con e-child\" data-id=\"c4b4b8b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-830ab47 elementor-widget elementor-widget-spacer\" data-id=\"830ab47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf1d34 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ccf1d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br><br>Une<br>transformation<br>int\u00e9rieure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4bbe61 elementor-widget elementor-widget-spacer\" data-id=\"f4bbe61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d087d2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8d087d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ce cheminement s\u2019est nourri de la m\u00e9ditation, de la connaissance de soi, de conf\u00e9rences, de lectures et de nombreuses formations en d\u00e9veloppement personnel et accompagnement humain.<br \/>Il a \u00e9galement \u00e9t\u00e9 inspir\u00e9 par les enseignements de Anthony Robbins, Joe Dispenza, Eckhart Tolle et Deepak Chopra.<br \/>Au fil du temps, j\u2019ai d\u00e9velopp\u00e9 une approche intuitive, humaine et ancr\u00e9e, reliant l\u2019exp\u00e9rience professionnelle, l\u2019\u00e9coute sensible et la dimension int\u00e9rieure de chacun.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3434329 elementor-widget elementor-widget-spacer\" data-id=\"3434329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef7eca0 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"ef7eca0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-858880d e-con-full e-flex e-con e-child\" data-id=\"858880d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9b291 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"1f9b291\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin1-1.jpg\" class=\"attachment-full size-full wp-image-1010\" alt=\"mon parcours constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin1-1.jpg 2048w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin1-1-300x225.jpg 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin1-1-1024x768.jpg 1024w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin1-1-768x576.jpg 768w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin1-1-1536x1152.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38d8494 e-con-full e-flex e-con e-child\" data-id=\"38d8494\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6aa505b elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"6aa505b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/blueline.json&quot;,&quot;id&quot;:677,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:52,&quot;end&quot;:100}},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cc9a43 e-con-full e-flex e-con e-child\" data-id=\"5cc9a43\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f0e84e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7f0e84e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une transformation<br>int\u00e9rieure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6b0069 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b6b0069\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ce cheminement s\u2019est nourri de la m\u00e9ditation, de la connaissance de soi, de conf\u00e9rences, de lectures et de nombreuses formations en d\u00e9veloppement personnel et accompagnement humain.<br \/>Il a \u00e9galement \u00e9t\u00e9 inspir\u00e9 par les enseignements de Anthony Robbins, Joe Dispenza, Eckhart Tolle et Deepak Chopra.<br \/>Au fil du temps, j\u2019ai d\u00e9velopp\u00e9 une approche intuitive, humaine et ancr\u00e9e, reliant l\u2019exp\u00e9rience professionnelle, l\u2019\u00e9coute sensible et la dimension int\u00e9rieure de chacun.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58ed8f6 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"58ed8f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-636f86c e-con-full e-flex e-con e-child\" data-id=\"636f86c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8318c8f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8318c8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aujourd'hui<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ef3237 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5ef3237\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Je crois profond\u00e9ment que chacun poss\u00e8de en lui les cl\u00e9s de sa transformation.<br \/>Parce que parfois, il suffit simplement d\u2019un espace juste, d\u2019un regard diff\u00e9rent et d\u2019une rencontre authentique pour remettre la vie en mouvement et retrouver un chemin plus align\u00e9, plus serein et plus vivant.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e4cf57 e-con-full e-flex e-con e-child\" data-id=\"1e4cf57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8c1804 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"f8c1804\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:54}},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3.png\" class=\"attachment-full size-full wp-image-683\" alt=\"constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3.png 512w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3-300x300.png 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf9fbdc e-con-full e-flex e-con e-child\" data-id=\"cf9fbdc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8805d7 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e8805d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1500\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28.jpg\" class=\"attachment-full size-full wp-image-1011\" alt=\"mon parcours constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28.jpg 2000w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28-300x225.jpg 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28-1024x768.jpg 1024w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28-768x576.jpg 768w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28-1536x1152.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea3fb93 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"ea3fb93\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-009357b e-con-full e-flex e-con e-child\" data-id=\"009357b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7071f34 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7071f34\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aujourd'hui<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c450719 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c450719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Je crois profond\u00e9ment que chacun poss\u00e8de en lui les cl\u00e9s de sa transformation.<br \/>Parfois, il suffit simplement d\u2019un espace juste, d\u2019un regard diff\u00e9rent et d\u2019une rencontre authentique pour remettre la vie en mouvement et retrouver un chemin plus align\u00e9, plus serein et plus vivant.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a91d500 e-con-full e-flex e-con e-child\" data-id=\"a91d500\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51402ac elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"51402ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1500\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28.jpg\" class=\"attachment-full size-full wp-image-1011\" alt=\"mon parcours constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28.jpg 2000w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28-300x225.jpg 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28-1024x768.jpg 1024w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28-768x576.jpg 768w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/06\/Photo-de-Jean-Marie-Blin28-1536x1152.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-260f845 e-con-full elementor-hidden-desktop elementor-hidden-tablet e-flex e-con e-child\" data-id=\"260f845\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf252f1 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"cf252f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:54}},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3.png\" class=\"attachment-full size-full wp-image-683\" alt=\"constellation astrologie coaching pro et perso\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3.png 512w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3-300x300.png 300w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2-3-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d578be4 elementor-widget elementor-widget-spacer\" data-id=\"d578be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40eab8e8 e-con-full e-flex e-con e-parent\" data-id=\"40eab8e8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4.1,&quot;sizes&quot;:[]},&quot;background_motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_blur_direction&quot;:&quot;in-out-in&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7.4,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:75}},&quot;background_motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:10,&quot;end&quot;:73}},&quot;background_motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-393f3181 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-spacer\" data-id=\"393f3181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5837aa58 elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"5837aa58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Pr\u00eats \u00e0 avancer vers plus d'alignement ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e77236c elementor-widget elementor-widget-spacer\" data-id=\"2e77236c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4262314e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4262314e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Vous avez toutes les ressources en vous, mon accompagnement vous aidera \u00e0 les mettre en lumi\u00e8re et \u00e0 cheminer comme je l&#8217;ai fait dans ma propre histoire personnelle. Mon approche est concr\u00e8te, structur\u00e9e et orient\u00e9e r\u00e9sultats. On identifie pr\u00e9cis\u00e9ment ce qui bloque puis on met en place des actions cibl\u00e9es pour avancer rapidement.<\/p><p style=\"text-align: center;\">\u00a0<\/p><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b66665e e-transform animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"2b66665e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;slideInUp&quot;,&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4.6,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-628d082f e-con-full e-flex e-con e-child\" data-id=\"628d082f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6986c0c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6986c0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/coeur-2.png\" class=\"attachment-full size-full wp-image-260\" alt=\"Astrologie et th\u00e8me natal\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/coeur-2.png 256w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/coeur-2-150x150.png 150w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u00c9coute profonde <br>et bienveillante<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-382f7e3e e-con-full e-flex e-con e-child\" data-id=\"382f7e3e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-262a5c51 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"262a5c51\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/serenite.png\" class=\"attachment-full size-full wp-image-256\" alt=\"\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/serenite.png 256w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/serenite-150x150.png 150w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Approche intuitive et personnalis\u00e9e<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a0bf8f9 e-con-full e-flex e-con e-child\" data-id=\"7a0bf8f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14e208b0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"14e208b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/systeme-solaire.png\" class=\"attachment-full size-full wp-image-258\" alt=\"\" srcset=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/systeme-solaire.png 256w, https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/systeme-solaire-150x150.png 150w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Outils vari\u00e9s <br>et compl\u00e9mentaires<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5dad5e69 e-con-full e-flex e-con e-child\" data-id=\"5dad5e69\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27332d10 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"27332d10\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/soleil.png\" class=\"attachment-full size-full wp-image-257\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">R\u00e9sultats concrets <br>et durables<br><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mon parcours D&#8217;un parcours de dirigeant \u00e0 l&#8217;accompagnement de l&#8217;\u00eatre : un chemin vers plus de sens, d&#8217;alignement et de transformation Chemin constellation astrologie coaching Monparcours D&#8217;un parcours de dirigeant \u00e0 l&#8217;accompagnement de l&#8217;\u00eatre : un chemin vers plus de sens, d&#8217;alignement et de transformation chemin constellation astrologie coaching Un parcours riche et exigeant Avant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":506,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-69","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jean-Marie Blin - Mon chemin - constellations astrologie coaching<\/title>\n<meta name=\"description\" content=\"Un parcours entre exigence professionnelle et qu\u00eate de sens\u200b... Le chemin constellation astrologie coaching\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blin-energie.fr\/index.php\/monparcours\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jean-Marie Blin - Mon chemin - constellations astrologie coaching\" \/>\n<meta property=\"og:description\" content=\"Un parcours entre exigence professionnelle et qu\u00eate de sens\u200b... Le chemin constellation astrologie coaching\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blin-energie.fr\/index.php\/monparcours\/\" \/>\n<meta property=\"og:site_name\" content=\"Jean-Marie Blin\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T09:49:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/Astrologie-Coaching-pro-et-perso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"545\" \/>\n\t<meta property=\"og:image:height\" content=\"818\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/index.php\\\/monparcours\\\/\",\"url\":\"https:\\\/\\\/blin-energie.fr\\\/index.php\\\/monparcours\\\/\",\"name\":\"Jean-Marie Blin - Mon chemin - constellations astrologie coaching\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/index.php\\\/monparcours\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/index.php\\\/monparcours\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Astrologie-Coaching-pro-et-perso.jpg\",\"datePublished\":\"2026-05-04T12:59:20+00:00\",\"dateModified\":\"2026-06-25T09:49:04+00:00\",\"description\":\"Un parcours entre exigence professionnelle et qu\u00eate de sens\u200b... Le chemin constellation astrologie coaching\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/index.php\\\/monparcours\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blin-energie.fr\\\/index.php\\\/monparcours\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/index.php\\\/monparcours\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Astrologie-Coaching-pro-et-perso.jpg\",\"contentUrl\":\"https:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Astrologie-Coaching-pro-et-perso.jpg\",\"width\":545,\"height\":818,\"caption\":\"Constellation Astrologie Coaching pro et perso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/index.php\\\/monparcours\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blin-energie.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jean-Marie Blin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/#website\",\"url\":\"https:\\\/\\\/blin-energie.fr\\\/\",\"name\":\"Jean-Marie Blin\",\"description\":\"Constellation Astrologie Coaching pro et perso\",\"publisher\":{\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/#\\\/schema\\\/person\\\/3fa5164533e818ada5fcba80b248142e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blin-energie.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/#\\\/schema\\\/person\\\/3fa5164533e818ada5fcba80b248142e\",\"name\":\"admin6935\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/constellation-astrologie-coaching-pro-et-perso-2.png\",\"url\":\"https:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/constellation-astrologie-coaching-pro-et-perso-2.png\",\"contentUrl\":\"https:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/constellation-astrologie-coaching-pro-et-perso-2.png\",\"width\":512,\"height\":512,\"caption\":\"admin6935\"},\"logo\":{\"@id\":\"https:\\\/\\\/blin-energie.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/constellation-astrologie-coaching-pro-et-perso-2.png\"},\"sameAs\":[\"http:\\\/\\\/blin-energie.fr\",\"https:\\\/\\\/fr.linkedin.com\\\/in\\\/jean-marie-blin-62834616\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jean-Marie Blin - Mon chemin - constellations astrologie coaching","description":"Un parcours entre exigence professionnelle et qu\u00eate de sens\u200b... Le chemin constellation astrologie coaching","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blin-energie.fr\/index.php\/monparcours\/","og_locale":"en_US","og_type":"article","og_title":"Jean-Marie Blin - Mon chemin - constellations astrologie coaching","og_description":"Un parcours entre exigence professionnelle et qu\u00eate de sens\u200b... Le chemin constellation astrologie coaching","og_url":"https:\/\/blin-energie.fr\/index.php\/monparcours\/","og_site_name":"Jean-Marie Blin","article_modified_time":"2026-06-25T09:49:04+00:00","og_image":[{"width":545,"height":818,"url":"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/Astrologie-Coaching-pro-et-perso.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blin-energie.fr\/index.php\/monparcours\/","url":"https:\/\/blin-energie.fr\/index.php\/monparcours\/","name":"Jean-Marie Blin - Mon chemin - constellations astrologie coaching","isPartOf":{"@id":"https:\/\/blin-energie.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blin-energie.fr\/index.php\/monparcours\/#primaryimage"},"image":{"@id":"https:\/\/blin-energie.fr\/index.php\/monparcours\/#primaryimage"},"thumbnailUrl":"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/Astrologie-Coaching-pro-et-perso.jpg","datePublished":"2026-05-04T12:59:20+00:00","dateModified":"2026-06-25T09:49:04+00:00","description":"Un parcours entre exigence professionnelle et qu\u00eate de sens\u200b... Le chemin constellation astrologie coaching","breadcrumb":{"@id":"https:\/\/blin-energie.fr\/index.php\/monparcours\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blin-energie.fr\/index.php\/monparcours\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blin-energie.fr\/index.php\/monparcours\/#primaryimage","url":"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/Astrologie-Coaching-pro-et-perso.jpg","contentUrl":"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/Astrologie-Coaching-pro-et-perso.jpg","width":545,"height":818,"caption":"Constellation Astrologie Coaching pro et perso"},{"@type":"BreadcrumbList","@id":"https:\/\/blin-energie.fr\/index.php\/monparcours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blin-energie.fr\/"},{"@type":"ListItem","position":2,"name":"Jean-Marie Blin"}]},{"@type":"WebSite","@id":"https:\/\/blin-energie.fr\/#website","url":"https:\/\/blin-energie.fr\/","name":"Jean-Marie Blin","description":"Constellation Astrologie Coaching pro et perso","publisher":{"@id":"https:\/\/blin-energie.fr\/#\/schema\/person\/3fa5164533e818ada5fcba80b248142e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blin-energie.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/blin-energie.fr\/#\/schema\/person\/3fa5164533e818ada5fcba80b248142e","name":"admin6935","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2.png","url":"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2.png","contentUrl":"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2.png","width":512,"height":512,"caption":"admin6935"},"logo":{"@id":"https:\/\/blin-energie.fr\/wp-content\/uploads\/2026\/05\/constellation-astrologie-coaching-pro-et-perso-2.png"},"sameAs":["http:\/\/blin-energie.fr","https:\/\/fr.linkedin.com\/in\/jean-marie-blin-62834616"]}]}},"_links":{"self":[{"href":"https:\/\/blin-energie.fr\/index.php\/wp-json\/wp\/v2\/pages\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blin-energie.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blin-energie.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blin-energie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blin-energie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":301,"href":"https:\/\/blin-energie.fr\/index.php\/wp-json\/wp\/v2\/pages\/69\/revisions"}],"predecessor-version":[{"id":1369,"href":"https:\/\/blin-energie.fr\/index.php\/wp-json\/wp\/v2\/pages\/69\/revisions\/1369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blin-energie.fr\/index.php\/wp-json\/wp\/v2\/media\/506"}],"wp:attachment":[{"href":"https:\/\/blin-energie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}